{"id":1,"date":"2018-07-18T13:47:34","date_gmt":"2018-07-18T11:47:34","guid":{"rendered":"http:\/\/35ppp.de\/paul\/?p=1"},"modified":"2018-08-06T12:15:48","modified_gmt":"2018-08-06T10:15:48","slug":"hallo-welt","status":"publish","type":"post","link":"https:\/\/35ppp.de\/paul\/2018\/07\/18\/hallo-welt\/","title":{"rendered":"Gude Welt!"},"content":{"rendered":"<p>Gude! Mein Name ist Paul Jagomast, ich bin 20 Jahre alt und komme aus Limburg in Hessen.<\/p>\n<p>Es sind nur noch wenige Tage(Heute ist der 03.08.18) bis es los geht und Ja, so langsam steigt die Vorfreude und nat\u00fcrlich auch ein bisschen Angst. Sorgen mache ich mir allerdings nicht. Ich freue mich schon sehr meine Gastfamilie, die aus Mutter(Wendy), Tochter(Carlee), drei Hunden und zwei Katzen besteht, kennen zu lernen. Wohnen werde ich bei ihnen in Spanaway, etwa eine Stunde von Seattle entfernt und auch etwa eine Stunde von der Hauptstadt Washingtons Olympia. In den ersten Monaten des Jahres werde ich das Clover Park Technical College in Lakewood besuchen und Kurse in Richtung Maschinenbau belegen.<\/p>\n<p>So das war mein erster Beitrag, ich werde versuchen in regelm\u00e4\u00dfigen Abst\u00e4nden oder nach wichtigen Ereignissen immer mal was hoch zu laden und bevor ich jetzt mit dem Packen beginne, m\u00f6chte ich mich noch mal bei Allen bedanken die mich unterst\u00fctzen und unterst\u00fctzt haben und ich m\u00f6chte mich noch einmal ganz herzlich bei Herrn Willsch bedanken, dass er mich f\u00fcr dieses Programm ausgew\u00e4hlt hat.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gude! Mein Name ist Paul Jagomast, ich bin 20 Jahre alt und komme aus Limburg in Hessen. Es sind nur noch wenige Tage(Heute ist der 03.08.18) bis es los geht und Ja, so langsam steigt die Vorfreude und nat\u00fcrlich auch ein bisschen Angst. Sorgen mache ich mir allerdings nicht. Ich freue mich schon sehr meine [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":6,"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":19,"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/posts\/1\/revisions\/19"}],"wp:attachment":[{"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/35ppp.de\/paul\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}